{"id":103309,"date":"2023-08-08T01:02:25","date_gmt":"2023-08-08T06:02:25","guid":{"rendered":"http:\/\/diariodigitalmx.com\/?p=103309"},"modified":"2023-08-08T01:03:08","modified_gmt":"2023-08-08T06:03:08","slug":"ninos-jugando-a-ser-adultos","status":"publish","type":"post","link":"https:\/\/diariodigitalmx.com\/index.php\/2023\/08\/08\/ninos-jugando-a-ser-adultos\/","title":{"rendered":"Ni\u00f1os jugando a ser adultos"},"content":{"rendered":"\n<p><br>Gerson G\u00f3mez<br>Ximena Peredo, F\u00e9lix Arratia, Mariana Rodr\u00edguez e Indira Kempis Garc\u00eda pasaran a la basura de la historia reciente. Amparados contra la justicia, la mayor\u00eda de ellos, se ocultan en sus oficinas.<br>Ximena debe y pagar\u00e1 en met\u00e1lico, de su peculio, solo es cuesti\u00f3n de tiempo. Perder\u00e1 en todas las instancias. Su acto de difamaci\u00f3n es contundente. A\u00fan se\u00f1ale la prescripci\u00f3n de su delito.<br>F\u00e9lix Arratia, simpl\u00f3n de trajes o ropaje henchido en su cuerpo abultado, ha tratado de ser el cortafuegos, el sancho panza del gobernador. Los diputados de la oposici\u00f3n, expediente en mano, van por su ca\u00edda. A los grupos parlamentarios les urge verlo en el penal de Apodaca o Cadereyta.<br>Mariana Rodr\u00edguez, Reyna consorte en la corte de los enanos, desconoce todos los elementos legales. Su capacidad intelectual apenas va por encima a la media. Decepcionara a sus followers, los chabacanos. No existe una sola imagen, discreta, de alimentar con su cuerpo a Mariel.<br>M\u00e1s all\u00e1 del tik tok, Mariana no debe ser considerada en serio para cargo de elecci\u00f3n popular alguno.<br>La fr\u00e1gil whitemexican no es Jackelin Kennedy. Tampoco Samuel es John F. Los espacios del senado, para Dante Delgado, el presidente, l\u00edder moral y hasta due\u00f1o de la concesi\u00f3n de Movimiento Ciudadano, Colosio o Trevi\u00f1o atraen bobos.<br>Si desea pesos pesados, recurrir\u00e1 a Agust\u00edn Basave Ben\u00edtez, por encima del cachorro Basave Alan\u00eds.<br>Para Indira Kempis Garc\u00eda el panorama es m\u00e1s restringido. Funcionar como br\u00f3ker, promotora de las criptomonedas o hacerse cargo de Participaci\u00f3n Ciudadana, donde a\u00fan despacha Ximena Peredo.<br>O regresar a su natal Morelos, a vender asesor\u00edas legislativas. Comenzar trabajo pol\u00edtico en la tierra de Emiliano Zapata. Ah\u00ed se sentir\u00e1 mejor. A una hora, por carretera, de la ciudad de M\u00e9xico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gerson G\u00f3mezXimena Peredo, F\u00e9lix Arratia, Mariana Rodr\u00edguez e Indira Kempis Garc\u00eda pasaran a la basura de la historia reciente. Amparados contra la justicia, la mayor\u00eda de ellos, se ocultan en sus oficinas.Ximena debe y pagar\u00e1 en met\u00e1lico, de su peculio, solo es cuesti\u00f3n de tiempo. Perder\u00e1 en todas las instancias. Su acto de difamaci\u00f3n es [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":103311,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,12],"tags":[],"_links":{"self":[{"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/posts\/103309"}],"collection":[{"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/comments?post=103309"}],"version-history":[{"count":1,"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/posts\/103309\/revisions"}],"predecessor-version":[{"id":103310,"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/posts\/103309\/revisions\/103310"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/media\/103311"}],"wp:attachment":[{"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/media?parent=103309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/categories?post=103309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/tags?post=103309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}