{"id":103336,"date":"2023-08-08T15:24:47","date_gmt":"2023-08-08T20:24:47","guid":{"rendered":"http:\/\/diariodigitalmx.com\/?p=103336"},"modified":"2023-08-08T15:27:43","modified_gmt":"2023-08-08T20:27:43","slug":"brinda-escobedo-asesoria-legal-a-afectados-por-explosion-de-pipa","status":"publish","type":"post","link":"https:\/\/diariodigitalmx.com\/index.php\/2023\/08\/08\/brinda-escobedo-asesoria-legal-a-afectados-por-explosion-de-pipa\/","title":{"rendered":"Brinda Escobedo asesor\u00eda legal a afectados por explosi\u00f3n de pipa"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"http:\/\/diariodigitalmx.com\/wp-content\/uploads\/2023\/08\/FOTO-1-1-1024x682.jpeg\" alt=\"\" class=\"wp-image-103341\" srcset=\"https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2023\/08\/FOTO-1-1-1024x682.jpeg 1024w, https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2023\/08\/FOTO-1-1-300x200.jpeg 300w, https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2023\/08\/FOTO-1-1-768x512.jpeg 768w, https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2023\/08\/FOTO-1-1-1536x1023.jpeg 1536w, https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2023\/08\/FOTO-1-1.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>El Gobierno de Escobedo reitera su apoyo a las familias que resultaron afectadas tras la explosi\u00f3n de una pipa de gas en la Colonia Lomas de San Genero.<\/p>\n\n\n\n<p>La Secretar\u00eda de Ayuntamiento de Escobedo informa que, el Gobierno Municipal contin\u00faa en comunicaci\u00f3n con los afectados del siniestro para brindarles orientaci\u00f3n legal para el reclamo y restituci\u00f3n de sus bienes da\u00f1ados en el siniestro.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"http:\/\/diariodigitalmx.com\/wp-content\/uploads\/2023\/08\/FOTO-4-1024x682.jpeg\" alt=\"\" class=\"wp-image-103343\" srcset=\"https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2023\/08\/FOTO-4-1024x682.jpeg 1024w, https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2023\/08\/FOTO-4-300x200.jpeg 300w, https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2023\/08\/FOTO-4-768x512.jpeg 768w, https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2023\/08\/FOTO-4-1536x1023.jpeg 1536w, https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2023\/08\/FOTO-4.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Por su parte, personal de DIF Escobedo acudi\u00f3 el d\u00eda del incidente para evaluar las necesidades de las familias afectadas, adem\u00e1s de llevarles despensas, cobijas y camastros.<\/p>\n\n\n\n<p>El d\u00eda del accidente, DIF ofreci\u00f3 a las familias afectadas su traslado al albergue de la Colonia Fernando Amilpa, pero se\u00f1alaron que se hospedar\u00edan con familiares.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"http:\/\/diariodigitalmx.com\/wp-content\/uploads\/2023\/08\/FOTO-3-768x1024.jpeg\" alt=\"\" class=\"wp-image-103345\" srcset=\"https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2023\/08\/FOTO-3-768x1024.jpeg 768w, https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2023\/08\/FOTO-3-225x300.jpeg 225w, https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2023\/08\/FOTO-3-1152x1536.jpeg 1152w, https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2023\/08\/FOTO-3.jpeg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p>El Municipio de Escobedo continua al pendiente de las necesidades de las personas que resultaron afectadas por los incendios provocados tras el choque de una pipa contra un poste de luz.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno de Escobedo reitera su apoyo a las familias que resultaron afectadas tras la explosi\u00f3n de una pipa de gas en la Colonia Lomas de San Genero. La Secretar\u00eda de Ayuntamiento de Escobedo informa que, el Gobierno Municipal contin\u00faa en comunicaci\u00f3n con los afectados del siniestro para brindarles orientaci\u00f3n legal para el reclamo y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":103338,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,5],"tags":[],"_links":{"self":[{"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/posts\/103336"}],"collection":[{"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/comments?post=103336"}],"version-history":[{"count":5,"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/posts\/103336\/revisions"}],"predecessor-version":[{"id":103346,"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/posts\/103336\/revisions\/103346"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/media\/103338"}],"wp:attachment":[{"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/media?parent=103336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/categories?post=103336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/tags?post=103336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}