{"id":62762,"date":"2021-09-22T11:47:59","date_gmt":"2021-09-22T16:47:59","guid":{"rendered":"http:\/\/diariodigitalmx.com\/?p=62762"},"modified":"2021-09-22T11:55:55","modified_gmt":"2021-09-22T16:55:55","slug":"son-santos-z-y-power-rangers-los-mandones-del-futbol-rapido-dominical-de-la-liga-casabella","status":"publish","type":"post","link":"https:\/\/diariodigitalmx.com\/index.php\/2021\/09\/22\/son-santos-z-y-power-rangers-los-mandones-del-futbol-rapido-dominical-de-la-liga-casabella\/","title":{"rendered":"Son Santos Z y Power Rangers los mandones del futbol r\u00e1pido dominical de la Liga CasaBella"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><strong>-Se llevan los t\u00edtulos de Copa as\u00ed como el de Liga al vencer en forma trepidante por marcadores de 6-5 y 5-4 a las escuadras de&nbsp; Caligaris y Tigrillos&nbsp; en dos encuentros que mantienen&nbsp; al borde del infarto a los espectadores<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"http:\/\/diariodigitalmx.com\/wp-content\/uploads\/2021\/09\/power-rangers-campeon-de-lifa-de-futbol-rapido-dominical-1024x683.jpg\" alt=\"\" class=\"wp-image-62767\" srcset=\"https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2021\/09\/power-rangers-campeon-de-lifa-de-futbol-rapido-dominical-1024x683.jpg 1024w, https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2021\/09\/power-rangers-campeon-de-lifa-de-futbol-rapido-dominical-300x200.jpg 300w, https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2021\/09\/power-rangers-campeon-de-lifa-de-futbol-rapido-dominical-768x512.jpg 768w, https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2021\/09\/power-rangers-campeon-de-lifa-de-futbol-rapido-dominical-1536x1024.jpg 1536w, https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2021\/09\/power-rangers-campeon-de-lifa-de-futbol-rapido-dominical-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Por: Ra\u00fal E. Guevara Ortiz.- En la&nbsp; Catedral del f\u00fatbol r\u00e1pido, los demonios salieron huyendo despavoridos, espantados por la cantidad de goles&nbsp; y la calidad deportiva derrochada que sobre el sint\u00e9tico se dej\u00f3 sentir en los encuentros finales de Copa y de Liga donde los equipos de Santos Z y Power Rangers se proclamaron campeones&nbsp; de los torneos dominicales de la Liga CasaBella.<\/p>\n\n\n\n<p>En el primero de los encuentros llevados a cabo la ma\u00f1ana del domingo 19 de septiembre, la escuadra del Santos Z enfrent\u00f3 por el t\u00edtulo \u201ccopero\u201d al equipo de Caligaris para abrir boca en la emotiva jornada.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"http:\/\/diariodigitalmx.com\/wp-content\/uploads\/2021\/09\/ACCIONES-FINAL-DE-COPA-SANTOS-Z-vs-CALIGARIS-1-1024x683.jpg\" alt=\"\" class=\"wp-image-62770\" srcset=\"https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2021\/09\/ACCIONES-FINAL-DE-COPA-SANTOS-Z-vs-CALIGARIS-1-1024x683.jpg 1024w, https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2021\/09\/ACCIONES-FINAL-DE-COPA-SANTOS-Z-vs-CALIGARIS-1-300x200.jpg 300w, https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2021\/09\/ACCIONES-FINAL-DE-COPA-SANTOS-Z-vs-CALIGARIS-1-768x512.jpg 768w, https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2021\/09\/ACCIONES-FINAL-DE-COPA-SANTOS-Z-vs-CALIGARIS-1-1536x1024.jpg 1536w, https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2021\/09\/ACCIONES-FINAL-DE-COPA-SANTOS-Z-vs-CALIGARIS-1-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Luego de un intenso forcejeo con un gran n\u00famero de llegadas sin concretar en las inmediaciones de ambas porter\u00edas, despu\u00e9s de los primeros 12 minutos de juego, el partido concluy\u00f3 con marcador empatado a cero. Situaci\u00f3n que cambi\u00f3 radicalmente al inicio del segundo cuarto cuando el equipo de Santos Z tom\u00f3 el mando del marcador por conducto de Mart\u00edn Gayt\u00e1n que puso el 1-0, que trajo la alegr\u00eda a sus compa\u00f1eros pero por&nbsp; solo un minuto ya que en forma casi inmediata Anner Hern\u00e1ndez dio el empate 1-1 para los del Caligaris.<\/p>\n\n\n\n<p>Con el marcador igualado&nbsp; la temperatura futbol\u00edstica y las emociones empezaron aumentar el sint\u00e9tico de la Catedral y con dos goles de Edgar Armendariz los del Caligaris tomaron el mando del partido con contundente 1-3, ante un herido Santos Z que se lanz\u00f3 con todo al frente y a trav\u00e9s de Gerardo S\u00e1nchez y Mart\u00edn Estrada traer el 3-3&nbsp; con el que concluir\u00eda el tercer cuarto dejando lo mejor para el final.<\/p>\n\n\n\n<p>Con el orgullo herido al verse alcanzados en la pizarra nuevamente la contundencia de Anner Hern\u00e1ndez dio el cuarto gol para los del Caligaris (3-4) ventaja que prevaleci\u00f3 durante casi todo el periodo hasta que faltando 2 minutos para la conclusi\u00f3n del partido, un error de concentraci\u00f3n trajo la sexta falta favorable al Santos Z que sin desaprovechar el tiro penal perfectamente ejecutado por Eduardo Hern\u00e1ndez env\u00edo el partido con el 4-4 a la definici\u00f3n a trav\u00e9s de los shoot outs donde con todo \u201ccielo a su favor\u201d, la contundencia de los Santos Z con anotaciones de Gerardo S\u00e1nchez, Alejandro \u00c1lvarez,&nbsp; Mario Cand\u00eda y Jaziel Rodr\u00edguez conquistaron el t\u00edtulo de Copa del torneo dominical de f\u00fatbol r\u00e1pido en CasaBella con un marcador final de 6-5.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"http:\/\/diariodigitalmx.com\/wp-content\/uploads\/2021\/09\/ACCIONES-FINAL-DE-COPA-SANTOS-Z-vs-CALIGARIS-2-1024x683.jpg\" alt=\"\" class=\"wp-image-62772\" srcset=\"https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2021\/09\/ACCIONES-FINAL-DE-COPA-SANTOS-Z-vs-CALIGARIS-2-1024x683.jpg 1024w, https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2021\/09\/ACCIONES-FINAL-DE-COPA-SANTOS-Z-vs-CALIGARIS-2-300x200.jpg 300w, https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2021\/09\/ACCIONES-FINAL-DE-COPA-SANTOS-Z-vs-CALIGARIS-2-768x512.jpg 768w, https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2021\/09\/ACCIONES-FINAL-DE-COPA-SANTOS-Z-vs-CALIGARIS-2-1536x1024.jpg 1536w, https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2021\/09\/ACCIONES-FINAL-DE-COPA-SANTOS-Z-vs-CALIGARIS-2-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Con el sint\u00e9tico \u201ccalientito\u201d por el juego que le antecedi\u00f3, los equipos de Power Rangers y Tigrillos, dieron inicio a la disputa por el campeonato de Liga de f\u00fatbol r\u00e1pido brindando desde el inicio, un espectacular encuentro lleno de emocionantes acciones.<\/p>\n\n\n\n<p>Fueron los \u201cfelinos\u201d los primeros en hacerse presentes en la pizarra al minuto de juego por conducto de \u201cmat\u00f3n\u201d del \u00e1rea, Alexis Delgado&nbsp; quien dio el 1-0&nbsp; que prevaleci\u00f3 a lo largo de la parte inicial, pero que&nbsp; Abraham Rodr\u00edguez incrementar\u00eda con el 2-0 que les daba una ventaja tranquila durante los dos cuartos iniciales.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"http:\/\/diariodigitalmx.com\/wp-content\/uploads\/2021\/09\/acciones-POWER-RANGERS-vs.-TIGRILLOS-1-1024x683.jpg\" alt=\"\" class=\"wp-image-62775\" srcset=\"https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2021\/09\/acciones-POWER-RANGERS-vs.-TIGRILLOS-1-1024x683.jpg 1024w, https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2021\/09\/acciones-POWER-RANGERS-vs.-TIGRILLOS-1-300x200.jpg 300w, https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2021\/09\/acciones-POWER-RANGERS-vs.-TIGRILLOS-1-768x512.jpg 768w, https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2021\/09\/acciones-POWER-RANGERS-vs.-TIGRILLOS-1-1536x1024.jpg 1536w, https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2021\/09\/acciones-POWER-RANGERS-vs.-TIGRILLOS-1-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Pero la reacci\u00f3n de los Power Rangers empez\u00f3 a sentirse\u00a0 ya en el tercer periodo cuando Edgar \u201cEl Pato\u201d Mart\u00ednez los meti\u00f3 al partido con el 2-1 que los acerc\u00f3 en el marcador, a unos rivales que cayeron en un exceso de confianza y que en menos de cinco minutos les empataron el partido con los goles de\u00a0 Miguel Quiroga y Mario Palos quienes pusieron 3-3 las cosas para los Power\u2019s.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"http:\/\/diariodigitalmx.com\/wp-content\/uploads\/2021\/09\/acciones-POWER-RANGERS-vs.-TIGRILLOS-2-1024x683.jpg\" alt=\"\" class=\"wp-image-62778\" srcset=\"https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2021\/09\/acciones-POWER-RANGERS-vs.-TIGRILLOS-2-1024x683.jpg 1024w, https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2021\/09\/acciones-POWER-RANGERS-vs.-TIGRILLOS-2-300x200.jpg 300w, https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2021\/09\/acciones-POWER-RANGERS-vs.-TIGRILLOS-2-768x512.jpg 768w, https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2021\/09\/acciones-POWER-RANGERS-vs.-TIGRILLOS-2-1536x1024.jpg 1536w, https:\/\/diariodigitalmx.com\/wp-content\/uploads\/2021\/09\/acciones-POWER-RANGERS-vs.-TIGRILLOS-2-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Con la adrenalina al m\u00e1ximo y los asistentes de pie, dio inicio el \u00faltimo periodo de juego donde ambos equipos como si se jugar\u00e1n la vida en cada acci\u00f3n, luchaban por la conquista del campeonato, siendo los Tigrillos quienes nuevamente recobraron la ventaja con el 4-3 de Eder Qui\u00f1ones, pero sus rivales no estaban dispuestos a dejar ir la victoria y a trav\u00e9s de Osvaldo Contreras empatan el marcador 4-4 en forma moment\u00e1nea, mientras que la parte final, a poco menos de un minuto de juego una desconcentraci\u00f3n de la zaga defensiva \u201cfelina\u201d ocasion\u00f3 la sexta falta, misma que sin piedad cobr\u00f3 Mario Palos y que dio el 4-5 con el que los Power Rangers alcanzaron el triunfo y el campeonato de Liga.<\/p>\n\n\n\n<p>Al final del partido Gerardo Guerra Lozano presidente de la Liga CasaBella y Germ\u00e1n Ben\u00edtez, ex jugador profesional de Tigres y Rayados&nbsp; y del equipo hist\u00f3rico de f\u00fatbol R\u00e1pido, La Raza de Monterrey hicieron entrega&nbsp; de la premiaci\u00f3n correspondiente a los equipos campeones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>-Se llevan los t\u00edtulos de Copa as\u00ed como el de Liga al vencer en forma trepidante por marcadores de 6-5 y 5-4 a las escuadras de&nbsp; Caligaris y Tigrillos&nbsp; en dos encuentros que mantienen&nbsp; al borde del infarto a los espectadores Por: Ra\u00fal E. Guevara Ortiz.- En la&nbsp; Catedral del f\u00fatbol r\u00e1pido, los demonios salieron [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":62765,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,5],"tags":[],"_links":{"self":[{"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/posts\/62762"}],"collection":[{"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/comments?post=62762"}],"version-history":[{"count":8,"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/posts\/62762\/revisions"}],"predecessor-version":[{"id":62779,"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/posts\/62762\/revisions\/62779"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/media\/62765"}],"wp:attachment":[{"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/media?parent=62762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/categories?post=62762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/tags?post=62762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}