{"id":63706,"date":"2021-10-10T20:30:19","date_gmt":"2021-10-11T01:30:19","guid":{"rendered":"http:\/\/diariodigitalmx.com\/?p=63706"},"modified":"2021-10-10T20:32:01","modified_gmt":"2021-10-11T01:32:01","slug":"63706","status":"publish","type":"post","link":"https:\/\/diariodigitalmx.com\/index.php\/2021\/10\/10\/63706\/","title":{"rendered":"Reflexi\u00f3n de la Semana"},"content":{"rendered":"\n<p>Luz Mar\u00eda Ortiz Quintos <\/p>\n\n\n\n<p>Este domingo 10 de Octubre se da a conocer por parte de la autoridad estatal, el &#8220;<strong>Regreso Escolar Seguro<\/strong>&#8220;.<br>El Gobernador del Estado Samuel Garc\u00eda acompa\u00f1ado de las Secretar\u00edas de Salud y de Educaci\u00f3n, anunci\u00f3 la medida que nos da mucho gusto escuchar a los Padres de Familia; queremos analizar los ejes que se\u00f1ala en tan importante y necesaria acci\u00f3n, para la comunidad educativa.<\/p>\n\n\n\n<p><strong>Planeado<\/strong> <\/p>\n\n\n\n<p>Presentar\u00e1n el diagn\u00f3stico de las escuelas p\u00fablicas, \u00bfen qu\u00e9 condiciones se encuentran?, y \u00bfcu\u00e1ndo la Secretar\u00eda de Educaci\u00f3n &nbsp;las entregar\u00e1 listas? rehabilitadas, reparadas, con servicios de agua, luz, e internet, para que los Directores de cada escuela ya puedan recibir a los alumnos.Por su parte, los colegios particulares, por supuesto que ya est\u00e1n listos, es un servicio privado que se paga, y que a pesar de las clases en casa, los pagos por inscripci\u00f3n, reinscripci\u00f3n y colegiaturas no dejaron de cubrirse por los Padres de Familia, as\u00ed es que en este peque\u00f1o sector de la poblaci\u00f3n obviamente se cuenta con el recurso para tener las instalaciones, m\u00e1s que listas.<br><strong>Prudente<\/strong><\/p>\n\n\n\n<p>\u00bfEs prudente que los colegios particulares como si tienen el pago del servicio de los padres de familia y est\u00e1n listos para el regreso presencial, se de este regreso relegando a las Escuelas p\u00fablicas?, \u00bfse har\u00e1 m\u00e1s la brecha de la desigualdad en la educaci\u00f3n? Con esta medida, solamente los que pagan el servicio tienen beneficios del regreso a clases presencial.En este caso, la autoridad es la que debe pensar en el bien com\u00fan, y no solamente en el bien de los particulares.\u00bfCu\u00e1l es el calendario que la autoridad educativa tiene para entregar las m\u00e1s de 5,000 instalaciones p\u00fablicas?, para que tambi\u00e9n gocen de esta medida.<br><strong>Conveniente<\/strong> <\/p>\n\n\n\n<p>Totalmente de acuerdo, no solo es conveniente; es URGENTE que los estudiantes regresen a las aulas, el confinamiento por m\u00e1s de 15 meses, ha generado un incremento en problemas de salud mental.<br>Un porcentaje \u2018alarmante\u2019 de ni\u00f1os y adolescentes est\u00e1 sufriendo, a escala mundial, problemas de salud mental debido a la pandemia. Seg\u00fan un estudio estima que uno de cada cuatro j\u00f3venes experimenta s\u00edntomas de depresi\u00f3n cl\u00ednicamente elevados y uno de cada cinco, s\u00edntomas de ansiedad tambi\u00e9n elevados. Se trata de un metan\u00e1lisis realizado por la Universidad de Calgary (Canad\u00e1) que re\u00fane datos de 29 estudios, en los que participaron 80.879 j\u00f3venes de todo el mundo; los resultados se publican en la revista JAMA Pediatrics. Estos muestran que los s\u00edntomas de depresi\u00f3n y ansiedad se han duplicado en ni\u00f1os y adolescentes en comparaci\u00f3n con la \u00e9poca anterior a la pandemia, resume un comunicado de la universidad.&#8211;Es tan importante proteger la salud f\u00edsica como la salud mental, felicitamos al nuevo gobierno por esta medida, que anuncia precisamente el d\u00eda Mundial de la Salud.<\/p>\n\n\n\n<p>*La autora es presidenta del Instituto Nacional de Consultor\u00eda Familiar AC. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luz Mar\u00eda Ortiz Quintos Este domingo 10 de Octubre se da a conocer por parte de la autoridad estatal, el &#8220;Regreso Escolar Seguro&#8220;.El Gobernador del Estado Samuel Garc\u00eda acompa\u00f1ado de las Secretar\u00edas de Salud y de Educaci\u00f3n, anunci\u00f3 la medida que nos da mucho gusto escuchar a los Padres de Familia; queremos analizar los ejes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":63708,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,12],"tags":[],"_links":{"self":[{"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/posts\/63706"}],"collection":[{"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/comments?post=63706"}],"version-history":[{"count":4,"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/posts\/63706\/revisions"}],"predecessor-version":[{"id":63711,"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/posts\/63706\/revisions\/63711"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/media\/63708"}],"wp:attachment":[{"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/media?parent=63706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/categories?post=63706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodigitalmx.com\/index.php\/wp-json\/wp\/v2\/tags?post=63706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}